{"id":398,"date":"2025-11-19T14:12:33","date_gmt":"2025-11-19T13:12:33","guid":{"rendered":"https:\/\/doc.levi-strauss.fr\/fr\/?page_id=398"},"modified":"2025-11-19T14:53:36","modified_gmt":"2025-11-19T13:53:36","slug":"edition-genetique-eg","status":"publish","type":"page","link":"https:\/\/doc.levi-strauss.fr\/fr\/edition-genetique-eg","title":{"rendered":"\u00c9dition g\u00e9n\u00e9tique (EG)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">L\u2019\u00e9dition g\u00e9n\u00e9tique de <em>Tristes tropiques<\/em> vise \u00e0 \u00e9tablir des parcours permettant de suivre le d\u00e9veloppement de l\u2019\u0153uvre sur vingt ans, des notes des carnets de terrain de 1935 jusqu\u2019\u00e0 la publication de 1955, \u00e0 travers toutes les r\u00e9\u00e9critures et r\u00e9\u00e9laborations successives. \u00c0 travers l\u2019analyse codicologique des manuscrits, l\u2019analyse des ratures et des r\u00e9\u00e9critures du texte, le croisement des source externes, nous serons en mesure d\u2019ordonner tous les documents dans une suite chronologique qui refl\u00e8te les \u00e9tapes de l\u2019\u00e9laboration du texte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le dossier g\u00e9n\u00e9tique num\u00e9rique rassemblera et visualisera par tables, diagrammes et graphes tous les documents relevant du projet d\u2019\u00e9criture. Suivant \u00e9tape par \u00e9tape la progression de l\u2019\u0153uvre, le lecteur pourra ainsi consulter l\u2019archive num\u00e9ris\u00e9e et acc\u00e9der aux parcours g\u00e9n\u00e9tiques, qui disposent les unes apr\u00e8s les autres les parties de documents contenant les r\u00e9\u00e9critures du texte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gr\u00e2ce au LEG (Langage d\u2019encodage g\u00e9n\u00e9tique), la transcription permettra de visualiser les ph\u00e9nom\u00e8nes g\u00e9n\u00e9tiques se manifestant dans les couches de r\u00e9\u00e9criture pr\u00e9sentes sur une m\u00eame page manuscrite (biffures, ajouts, surcharges, substitutions).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019\u00e9dition g\u00e9n\u00e9tique de Tristes tropiques vise \u00e0 \u00e9tablir des parcours permettant de suivre le d\u00e9veloppement de l\u2019\u0153uvre sur vingt ans, des notes des carnets de terrain de 1935 jusqu\u2019\u00e0 la publication de 1955, \u00e0 travers toutes les r\u00e9\u00e9critures et r\u00e9\u00e9laborations successives. \u00c0 travers l\u2019analyse codicologique des manuscrits, l\u2019analyse des ratures et des r\u00e9\u00e9critures du texte, &hellip; <a href=\"https:\/\/doc.levi-strauss.fr\/fr\/edition-genetique-eg\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;\u00c9dition g\u00e9n\u00e9tique (EG)&#8221;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-398","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/doc.levi-strauss.fr\/fr\/wp-json\/wp\/v2\/pages\/398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/doc.levi-strauss.fr\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/doc.levi-strauss.fr\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/doc.levi-strauss.fr\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/doc.levi-strauss.fr\/fr\/wp-json\/wp\/v2\/comments?post=398"}],"version-history":[{"count":2,"href":"https:\/\/doc.levi-strauss.fr\/fr\/wp-json\/wp\/v2\/pages\/398\/revisions"}],"predecessor-version":[{"id":406,"href":"https:\/\/doc.levi-strauss.fr\/fr\/wp-json\/wp\/v2\/pages\/398\/revisions\/406"}],"wp:attachment":[{"href":"https:\/\/doc.levi-strauss.fr\/fr\/wp-json\/wp\/v2\/media?parent=398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}